{"id":6465,"date":"2024-03-07T11:20:11","date_gmt":"2024-03-07T11:20:11","guid":{"rendered":"https:\/\/modablanca.ma\/?post_type=product&#038;p=6465"},"modified":"2025-04-12T09:30:35","modified_gmt":"2025-04-12T09:30:35","slug":"ensemble-classe-2","status":"publish","type":"product","link":"https:\/\/www.modablanca.ma\/ar\/product\/ensemble-classe-2\/","title":{"rendered":"Ensemble classe Noir"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":6466,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[122],"product_tag":[],"class_list":{"0":"post-6465","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-ensemble-classe","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-variable"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.modablanca.ma\/ar\/wp-json\/wp\/v2\/product\/6465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.modablanca.ma\/ar\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.modablanca.ma\/ar\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.modablanca.ma\/ar\/wp-json\/wp\/v2\/comments?post=6465"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.modablanca.ma\/ar\/wp-json\/wp\/v2\/media\/6466"}],"wp:attachment":[{"href":"https:\/\/www.modablanca.ma\/ar\/wp-json\/wp\/v2\/media?parent=6465"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.modablanca.ma\/ar\/wp-json\/wp\/v2\/product_brand?post=6465"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.modablanca.ma\/ar\/wp-json\/wp\/v2\/product_cat?post=6465"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.modablanca.ma\/ar\/wp-json\/wp\/v2\/product_tag?post=6465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}